{"id":14415,"date":"2025-01-07T22:05:48","date_gmt":"2025-01-07T18:35:48","guid":{"rendered":"https:\/\/parsalab.com\/blog\/%d8%a7%d9%84-%d8%a7%db%8c-%d8%af%db%8c-%d8%a8%d9%87%d8%aa%d8%b1%d9%87-%db%8c%d8%a7-%d8%a7%d9%84-%d8%b3%db%8c-%d8%af%db%8c\/"},"modified":"2025-01-07T22:05:48","modified_gmt":"2025-01-07T18:35:48","slug":"%d8%a7%d9%84-%d8%a7%db%8c-%d8%af%db%8c-%d8%a8%d9%87%d8%aa%d8%b1%d9%87-%db%8c%d8%a7-%d8%a7%d9%84-%d8%b3%db%8c-%d8%af%db%8c","status":"publish","type":"post","link":"https:\/\/parsalab.com\/blog\/%d8%a7%d9%84-%d8%a7%db%8c-%d8%af%db%8c-%d8%a8%d9%87%d8%aa%d8%b1%d9%87-%db%8c%d8%a7-%d8%a7%d9%84-%d8%b3%db%8c-%d8%af%db%8c\/","title":{"rendered":"\u0627\u0644 \u0627\u06cc \u062f\u06cc \u0628\u0647\u062a\u0631\u0647 \u06cc\u0627 \u0627\u0644 \u0633\u06cc \u062f\u06cc"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a class=\"maxbutton-50 maxbutton maxbutton-d985d8b4d8a7d987d8afdb80-d982db8cd985d8aa-d9bed8b1d981d8b1d988d8b4-d8aad8b1db8cd986-d8aad984d988db8cd8b2db8cd988d986\" target=\"_blank\" title=\"\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646\" rel=\"nofollow noopener\" href=\"https:\/\/dgkl.io\/api\/v1\/Click\/MWkO6\"><span class='mb-text'>\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646<\/span><\/a><\/strong><\/p>\n<p>&#8220;`html<\/p>\n<p>\u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0645\u0631\u0648\u0632\u060c <a href=\"https:\/\/parsalab.com\/blog\/tag\/\u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646\">\u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646<\/a>\u200c\u0647\u0627 \u0648 \u0645\u0627\u0646\u06cc\u062a\u0648\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u0639\u0631\u0636\u0647 \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627 \u0648 \u0645\u0632\u0627\u06cc\u0627\u06cc \u062e\u0627\u0635 \u062e\u0648\u062f \u0631\u0627 \u062f\u0627\u0631\u0646\u062f. \u062f\u0648 \u0646\u0648\u0639 \u0631\u0627\u06cc\u062c \u0627\u0632 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631\u0647\u0627\u060c \u0627\u0644 \u0627\u06cc \u062f\u06cc (LED) \u0648 \u0627\u0644 \u0633\u06cc \u062f\u06cc (LCD) \u0645\u06cc \u0628\u0627\u0634\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0627\u06cc\u0646 \u062f\u0648 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0648 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0622\u0646\u200c\u0647\u0627 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u062a\u0627 \u0628\u0647 \u0633\u0648\u0627\u0644 \u00ab\u0627\u0644 \u0627\u06cc \u062f\u06cc \u0628\u0647\u062a\u0631\u0647 \u06cc\u0627 \u0627\u0644 \u0633\u06cc \u062f\u06cc\u061f\u00bb \u067e\u0627\u0633\u062e \u062f\u0647\u06cc\u0645.<\/p>\n<h2>\u0645\u0639\u0631\u0641\u06cc \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0627\u0644 \u0633\u06cc \u062f\u06cc (LCD)<\/h2>\n<p>\u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc LCD (Liquid Crystal Display) \u06cc\u06a9\u06cc \u0627\u0632 \u0646\u062e\u0633\u062a\u06cc\u0646 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc\u200c\u0647\u0627\u06cc \u0646\u0645\u0627\u06cc\u0634\u06af\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0637\u0648\u0631 \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u0627\u06cc \u062f\u0631 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646\u200c\u0647\u0627\u060c \u0645\u0627\u0646\u06cc\u062a\u0648\u0631\u0647\u0627 \u0648 \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631 \u0627\u0632 \u0645\u0627\u06cc\u0639 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0628\u06cc\u0646 \u062f\u0648 \u0644\u0627\u06cc\u0647 \u0634\u0641\u0627\u0641 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u0644\u0627\u06cc\u0647\u200c\u0647\u0627 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0646\u0648\u0631 \u067e\u0633\u200c\u0632\u0645\u06cc\u0646\u0647 (Backlight) \u0631\u0648\u0634\u0646 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u062a\u0635\u0648\u06cc\u0631 \u0631\u0627 \u0628\u0647 \u0646\u0645\u0627\u06cc\u0634 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u0646\u062f.<\/p>\n<h3>\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0644 \u0633\u06cc \u062f\u06cc<\/h3>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0632\u0631\u06af\u200c\u062a\u0631\u06cc\u0646 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0644 \u0633\u06cc \u062f\u06cc\u060c \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0622\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0647\u0632\u06cc\u0646\u0647 \u06a9\u0645\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0644 \u0627\u06cc \u062f\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u06a9 \u06af\u0632\u06cc\u0646\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0645\u06cc \u0628\u0627\u0634\u0646\u062f\u060c \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0627\u0644 \u0633\u06cc \u062f\u06cc\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0633\u0628\u06a9\u200c\u062a\u0631 \u0648 \u0628\u0627\u0631\u06cc\u06a9\u200c\u062a\u0631 \u0627\u0632 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc\u200c\u0647\u0627\u06cc \u0642\u062f\u06cc\u0645\u06cc\u200c\u062a\u0631 \u0645\u06cc \u0628\u0627\u0634\u0646\u062f \u0648 \u0641\u0636\u0627\u06cc \u06a9\u0645\u062a\u0631\u06cc \u0631\u0627 \u0627\u0634\u063a\u0627\u0644 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<h3>\u0645\u0639\u0627\u06cc\u0628 \u0627\u0644 \u0633\u06cc \u062f\u06cc<\/h3>\n<p>\u0628\u0627 \u0648\u062c\u0648\u062f \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0644 \u0633\u06cc \u062f\u06cc\u060c \u0627\u06cc\u0646 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0645\u0639\u0627\u06cc\u0628\u06cc \u0646\u06cc\u0632 \u062f\u0627\u0631\u062f. \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0639\u0627\u06cc\u0628\u060c \u06a9\u06cc\u0641\u06cc\u062a \u062a\u0635\u0648\u06cc\u0631 \u0627\u0633\u062a. \u0627\u0644 \u0633\u06cc \u062f\u06cc\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u06a9\u0646\u062a\u0631\u0627\u0633\u062a \u06a9\u0645\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u062f\u0631 \u0646\u0645\u0627\u06cc\u0634 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u062a\u06cc\u0631\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u062e\u0648\u0628\u06cc \u0646\u062f\u0627\u0631\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0632\u0648\u0627\u06cc\u0627\u06cc \u062f\u06cc\u062f \u062f\u0631 \u0627\u06cc\u0646 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631\u0647\u0627 \u0645\u062d\u062f\u0648\u062f\u062a\u0631 \u0627\u0633\u062a \u0648 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0647\u0646\u06af\u0627\u0645 \u0645\u0634\u0627\u0647\u062f\u0647 \u0627\u0632 \u0632\u0648\u0627\u06cc\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u060c \u06a9\u06cc\u0641\u06cc\u062a \u062a\u0635\u0648\u06cc\u0631 \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f.<\/p>\n<h2>\u0645\u0639\u0631\u0641\u06cc \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0627\u0644 \u0627\u06cc \u062f\u06cc (LED)<\/h2>\n<p>\u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc LED (Light Emitting Diode) \u0628\u0647 \u0646\u0648\u0639\u06cc \u0627\u0632 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631\u0647\u0627 \u0627\u0637\u0644\u0627\u0642 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0627\u0632 \u062f\u06cc\u0648\u062f\u0647\u0627\u06cc \u0633\u0627\u0637\u0639\u200c\u06a9\u0646\u0646\u062f\u0647 \u0646\u0648\u0631 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u062a\u0635\u0648\u06cc\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0648\u0627\u0642\u0639\u060c \u0627\u0644 \u0627\u06cc \u062f\u06cc\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0646\u0648\u0639\u06cc \u0627\u0632 \u0627\u0644 \u0633\u06cc \u062f\u06cc \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u060c \u0686\u0648\u0646 \u0622\u0646\u200c\u0647\u0627 \u0646\u06cc\u0632 \u0627\u0632 \u0645\u0627\u06cc\u0639 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0627\u0645\u0627 \u0646\u0648\u0631 \u067e\u0633\u200c\u0632\u0645\u06cc\u0646\u0647 \u0622\u0646\u200c\u0647\u0627 \u0627\u0632 \u062f\u06cc\u0648\u062f\u0647\u0627\u06cc \u0646\u0648\u0631\u06cc \u062a\u0623\u0645\u06cc\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h3>\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0644 \u0627\u06cc \u062f\u06cc<\/h3>\n<p>\u0627\u0644 \u0627\u06cc \u062f\u06cc\u200c\u0647\u0627 \u0639\u0645\u0648\u0645\u0627\u064b \u06a9\u06cc\u0641\u06cc\u062a \u062a\u0635\u0648\u06cc\u0631 \u0628\u0627\u0644\u0627\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0644 \u0633\u06cc \u062f\u06cc\u200c\u0647\u0627 \u062f\u0627\u0631\u0646\u062f. \u0622\u0646\u200c\u0647\u0627 \u06a9\u0646\u062a\u0631\u0627\u0633\u062a \u0628\u0627\u0644\u0627\u062a\u0631 \u0648 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc\u200c\u062a\u0631\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0632\u0648\u0627\u06cc\u0627\u06cc \u062f\u06cc\u062f \u062f\u0631 \u0627\u0644 \u0627\u06cc \u062f\u06cc\u200c\u0647\u0627 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0648 \u0628\u06cc\u0646\u0646\u062f\u06af\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u0632 \u0632\u0648\u0627\u06cc\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u06a9\u06cc\u0641\u06cc\u062a \u062a\u0635\u0648\u06cc\u0631 \u0631\u0627 \u0645\u0634\u0627\u0647\u062f\u0647 \u06a9\u0646\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0627\u0644 \u0627\u06cc \u062f\u06cc\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u06a9\u0645\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0633\u0628\u0632\u062a\u0631 \u0648 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u200c\u062a\u0631 \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0631\u0648\u0646\u062f.<\/p>\n<h3>\u0645\u0639\u0627\u06cc\u0628 \u0627\u0644 \u0627\u06cc \u062f\u06cc<\/h3>\n<p>\u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c \u0627\u0644 \u0627\u06cc \u062f\u06cc\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0642\u06cc\u0645\u062a \u0628\u0627\u0644\u0627\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0644 \u0633\u06cc \u062f\u06cc\u200c\u0647\u0627 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0628\u0631\u062e\u06cc \u0627\u0632 \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u0627\u0644 \u0627\u06cc \u062f\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0646\u0648\u0631 \u0645\u062d\u06cc\u0637\u06cc \u0632\u06cc\u0627\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u062e\u0648\u0628\u06cc \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc\u060c \u062a\u0635\u0648\u06cc\u0631 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06a9\u06cc\u0641\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u062f\u0647\u062f.<\/p>\n<p style=\"text-align: center; font-weight: bold;\"><a class=\"maxbutton-50 maxbutton maxbutton-d985d8b4d8a7d987d8afdb80-d982db8cd985d8aa-d9bed8b1d981d8b1d988d8b4-d8aad8b1db8cd986-d8aad984d988db8cd8b2db8cd988d986\" target=\"_blank\" title=\"\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646\" rel=\"nofollow noopener\" href=\"https:\/\/dgkl.io\/api\/v1\/Click\/MWkO6\"><span class='mb-text'>\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646<\/span><\/a><\/p>\n<h2>\u0645\u0642\u0627\u06cc\u0633\u0647 \u0627\u0644 \u0627\u06cc \u062f\u06cc \u0648 \u0627\u0644 \u0633\u06cc \u062f\u06cc<\/h2>\n<table>\n<tr>\n<th>\u0648\u06cc\u0698\u06af\u06cc<\/th>\n<th>\u0627\u0644 \u0633\u06cc \u062f\u06cc<\/th>\n<th>\u0627\u0644 \u0627\u06cc \u062f\u06cc<\/th>\n<\/tr>\n<tr>\n<td>\u06a9\u06cc\u0641\u06cc\u062a \u062a\u0635\u0648\u06cc\u0631<\/td>\n<td>\u0645\u062a\u0648\u0633\u0637<\/td>\n<td>\u0645\u0646\u0627\u0633\u0628<\/td>\n<\/tr>\n<tr>\n<td>\u06a9\u0646\u062a\u0631\u0627\u0633\u062a<\/td>\n<td>\u06a9\u0645<\/td>\n<td>\u0628\u0627\u0644\u0627<\/td>\n<\/tr>\n<tr>\n<td>\u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc<\/td>\n<td>\u0628\u06cc\u0634\u062a\u0631<\/td>\n<td>\u06a9\u0645\u062a\u0631<\/td>\n<\/tr>\n<tr>\n<td>\u0642\u06cc\u0645\u062a<\/td>\n<td>\u067e\u0627\u06cc\u06cc\u0646\u200c\u062a\u0631<\/td>\n<td>\u0628\u0627\u0644\u0627\u062a\u0631<\/td>\n<\/tr>\n<tr>\n<td>\u0632\u0627\u0648\u06cc\u0647 \u062f\u06cc\u062f<\/td>\n<td>\u0645\u062d\u062f\u0648\u062f<\/td>\n<td>\u0628\u0647\u062a\u0631<\/td>\n<\/tr>\n<\/table>\n<h2>\u0646\u06a9\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u06cc\u0646 \u0627\u0644 \u0627\u06cc \u062f\u06cc \u0648 \u0627\u0644 \u0633\u06cc \u062f\u06cc<\/h2>\n<h3>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0648 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0634\u062e\u0635\u06cc<\/h3>\n<p>\u0642\u0628\u0644 \u0627\u0632 \u062a\u0635\u0645\u06cc\u0645\u200c\u06af\u06cc\u0631\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u062e\u0631\u06cc\u062f \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646 \u06cc\u0627 \u0645\u0627\u0646\u06cc\u062a\u0648\u0631\u060c \u0645\u06cc \u0628\u0627\u06cc\u0633\u062a \u0628\u0647 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0634\u062e\u0635\u06cc \u062e\u0648\u062f \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06af\u0631 \u0634\u0645\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0631\u0627\u06cc \u062a\u0645\u0627\u0634\u0627\u06cc \u0641\u06cc\u0644\u0645\u200c\u0647\u0627 \u0648 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627\u06cc \u0648\u06cc\u062f\u06cc\u0648\u06cc\u06cc \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u06a9 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u062a\u0635\u0648\u06cc\u0631 \u0628\u0627\u0644\u0627 \u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u0644 \u0627\u06cc \u062f\u06cc \u06af\u0632\u06cc\u0646\u0647 \u0628\u0647\u062a\u0631\u06cc \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u0627\u0645\u0627 \u0627\u06af\u0631 \u0628\u0648\u062f\u062c\u0647 \u0634\u0645\u0627 \u0645\u062d\u062f\u0648\u062f \u0627\u0633\u062a \u0648 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u06a9 \u06af\u0632\u06cc\u0646\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u062a\u0645\u0627\u0634\u0627\u06cc \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646 \u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u0644 \u0633\u06cc \u062f\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<h3>\u0641\u0636\u0627\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647<\/h3>\n<p>\u0646\u0648\u0639 \u0641\u0636\u0627\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u06cc\u0632 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u06cc\u0646 \u0627\u0644 \u0627\u06cc \u062f\u06cc \u0648 \u0627\u0644 \u0633\u06cc \u062f\u06cc \u062f\u0627\u0631\u062f. \u0627\u06af\u0631 \u062f\u0631 \u06cc\u06a9 \u0627\u062a\u0627\u0642 \u0628\u0627 \u0646\u0648\u0631 \u0637\u0628\u06cc\u0639\u06cc \u0632\u06cc\u0627\u062f \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u06cc\u062f\u060c \u0627\u0644 \u0627\u06cc \u062f\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u062a\u0635\u0648\u06cc\u0631 \u0628\u0647\u062a\u0631 \u0648 \u06a9\u0646\u062a\u0631\u0627\u0633\u062a \u0628\u0627\u0644\u0627\u062a\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u062c\u0631\u0628\u0647 \u062a\u0645\u0627\u0634\u0627 \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0628\u062e\u0634\u062f. \u0627\u0645\u0627 \u0627\u06af\u0631 \u0641\u0636\u0627\u06cc \u0634\u0645\u0627 \u062a\u0627\u0631\u06cc\u06a9\u200c\u062a\u0631 \u0627\u0633\u062a\u060c \u0627\u0644 \u0633\u06cc \u062f\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0627\u0634\u062f.<\/p>\n<h3>\u0637\u0648\u0644 \u0639\u0645\u0631 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc<\/h3>\n<p>\u062f\u0631 \u0646\u0647\u0627\u06cc\u062a\u060c \u0645\u06cc \u0628\u0627\u06cc\u0633\u062a \u0628\u0647 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0646\u0645\u0627\u06cc\u0634\u06af\u0631\u0647\u0627 \u0646\u06cc\u0632 \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u0644 \u0627\u06cc \u062f\u06cc\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u06a9\u0645\u062a\u0631 \u062f\u0686\u0627\u0631 \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u0645\u0627\u0646\u0646\u062f \u0633\u0648\u062e\u062a\u06af\u06cc \u067e\u06cc\u06a9\u0633\u0644 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u06a9 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631 \u0628\u0627 \u0639\u0645\u0631 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u062a\u0631 \u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u0644 \u0627\u06cc \u062f\u06cc \u06af\u0632\u06cc\u0646\u0647 \u0628\u0647\u062a\u0631\u06cc \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/p>\n<h2>\u0646\u062a\u06cc\u062c\u0647\u200c\u06af\u06cc\u0631\u06cc<\/h2>\n<p>\u062f\u0631 \u0646\u0647\u0627\u06cc\u062a\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u06cc\u0646 \u0627\u0644 \u0627\u06cc \u062f\u06cc \u0648 \u0627\u0644 \u0633\u06cc \u062f\u06cc \u0628\u0633\u062a\u06af\u06cc \u0628\u0647 \u0646\u06cc\u0627\u0632\u0647\u0627 \u0648 \u0634\u0631\u0627\u06cc\u0637 \u0634\u0645\u0627 \u062f\u0627\u0631\u062f. \u0647\u0631 \u062f\u0648 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628 \u062e\u0627\u0635 \u062e\u0648\u062f \u0631\u0627 \u062f\u0627\u0631\u0646\u062f. \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06a9\u06cc\u0641\u06cc\u062a \u062a\u0635\u0648\u06cc\u0631 \u0628\u0627\u0644\u0627 \u0648 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u06a9\u0645\u062a\u0631 \u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u0644 \u0627\u06cc \u062f\u06cc \u06af\u0632\u06cc\u0646\u0647 \u0628\u0647\u062a\u0631\u06cc \u0627\u0633\u062a. \u0627\u0645\u0627 \u0627\u06af\u0631 \u0628\u0648\u062f\u062c\u0647 \u0634\u0645\u0627 \u0645\u062d\u062f\u0648\u062f \u0627\u0633\u062a \u0648 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u06a9 \u06af\u0632\u06cc\u0646\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u0644 \u0633\u06cc \u062f\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0627\u0634\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0645\u0648\u0627\u0631\u062f \u0645\u0637\u0631\u062d \u0634\u062f\u0647\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u062a\u0635\u0645\u06cc\u0645 \u0628\u0647\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f \u062e\u0648\u062f \u0627\u062a\u062e\u0627\u0630 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>&#8220;`<\/p>\n<p style=\"text-align: center;\"><strong><a class=\"maxbutton-50 maxbutton maxbutton-d985d8b4d8a7d987d8afdb80-d982db8cd985d8aa-d9bed8b1d981d8b1d988d8b4-d8aad8b1db8cd986-d8aad984d988db8cd8b2db8cd988d986\" target=\"_blank\" title=\"\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646\" rel=\"nofollow noopener\" href=\"https:\/\/dgkl.io\/api\/v1\/Click\/MWkO6\"><span class='mb-text'>\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646<\/span><\/a><\/strong><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;`html \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0645\u0631\u0648\u0632\u060c \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646\u200c\u0647\u0627 \u0648 \u0645\u0627\u0646\u06cc\u062a\u0648\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u0639\u0631\u0636\u0647 \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627 \u0648 \u0645\u0632\u0627\u06cc\u0627\u06cc \u062e\u0627\u0635 \u062e\u0648\u062f \u0631\u0627 \u062f\u0627\u0631\u0646\u062f. \u062f\u0648 \u0646\u0648\u0639 \u0631\u0627\u06cc\u062c \u0627\u0632 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631\u0647\u0627\u060c \u0627\u0644 \u0627\u06cc \u062f\u06cc (LED) \u0648 \u0627\u0644 \u0633\u06cc \u062f\u06cc (LCD) \u0645\u06cc \u0628\u0627\u0634\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0627\u06cc\u0646 \u062f\u0648 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0648 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0622\u0646\u200c\u0647\u0627 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u062a\u0627 \u0628\u0647 \u0633\u0648\u0627\u0644 \u00ab\u0627\u0644 \u0627\u06cc &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-14415","post","type-post","status-publish","format-standard","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/posts\/14415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/comments?post=14415"}],"version-history":[{"count":0,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/posts\/14415\/revisions"}],"wp:attachment":[{"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/media?parent=14415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/categories?post=14415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/tags?post=14415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}