{"id":67240,"date":"2025-02-16T12:26:14","date_gmt":"2025-02-16T08:56:14","guid":{"rendered":"https:\/\/parsalab.com\/blog\/%da%86%d8%b1%d8%a7-%d8%af%d8%b1-%d9%87%d9%86%d8%af%d8%b2%d9%81%d8%b1%db%8c-%d8%b5%d8%af%d8%a7%db%8c-%d8%ae%d9%88%d8%a7%d9%86%d9%86%d8%af%d9%87-%d9%86%d9%85%db%8c%d8%a7%d8%af\/"},"modified":"2025-02-16T12:26:14","modified_gmt":"2025-02-16T08:56:14","slug":"%da%86%d8%b1%d8%a7-%d8%af%d8%b1-%d9%87%d9%86%d8%af%d8%b2%d9%81%d8%b1%db%8c-%d8%b5%d8%af%d8%a7%db%8c-%d8%ae%d9%88%d8%a7%d9%86%d9%86%d8%af%d9%87-%d9%86%d9%85%db%8c%d8%a7%d8%af","status":"publish","type":"post","link":"https:\/\/parsalab.com\/blog\/%da%86%d8%b1%d8%a7-%d8%af%d8%b1-%d9%87%d9%86%d8%af%d8%b2%d9%81%d8%b1%db%8c-%d8%b5%d8%af%d8%a7%db%8c-%d8%ae%d9%88%d8%a7%d9%86%d9%86%d8%af%d9%87-%d9%86%d9%85%db%8c%d8%a7%d8%af\/","title":{"rendered":"\u0686\u0631\u0627 \u062f\u0631 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u0646\u0645\u06cc\u0627\u062f"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a class=\"maxbutton-355 maxbutton maxbutton-d985d8b4d8a7d987d8afdb80-d982db8cd985d8aa-d9bed8b1d981d8b1d988d8b4-d8aad8b1db8cd986-d987d986d8afd8b2d981d8b1db8c-d988-d987d8afd981d988\" target=\"_blank\" title=\"\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc\" rel=\"nofollow noopener\" href=\"https:\/\/dgkl.io\/api\/v1\/Click\/Orujd\"><span class='mb-text'>\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc<\/span><\/a><\/strong><\/p>\n<p>&#8220;`html<\/p>\n<h2>\u0686\u0631\u0627 \u062f\u0631 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u0646\u0645\u06cc\u0627\u062f\u061f<\/h2>\n<h3>\u0645\u0642\u062f\u0645\u0647<\/h3>\n<p>\u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0645\u0631\u0648\u0632\u060c \u0647\u0646\u062f\u0632\u0641\u0631\u06cc\u200c\u0647\u0627 \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0636\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u06af\u0648\u0634 \u062f\u0627\u062f\u0646 \u0628\u0647 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0648 \u062a\u0645\u0627\u0633\u200c\u0647\u0627\u06cc \u062a\u0644\u0641\u0646\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647\u200c\u0627\u0646\u062f. \u0627\u0645\u0627 \u06af\u0627\u0647\u06cc \u0627\u0648\u0642\u0627\u062a \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u0645\u0634\u06a9\u0644\u06cc \u0645\u0648\u0627\u062c\u0647 \u0634\u0648\u06cc\u0645 \u06a9\u0647 \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u06cc\u0627 \u0635\u062f\u0627\u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u0627\u0632 \u0622\u0647\u0646\u06af\u200c\u0647\u0627 \u0628\u0647 \u06af\u0648\u0634 \u0645\u0627 \u0646\u0631\u0633\u062f. \u0627\u06cc\u0646 \u0645\u0634\u06a9\u0644 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0644\u0627\u06cc\u0644 \u0645\u062e\u062a\u0644\u0641\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0622\u0646\u0647\u0627 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0639\u0644\u0644\u060c \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627 \u0648 \u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u06cc\u0646 \u0645\u0634\u06a9\u0644 \u062e\u0648\u0627\u0647\u06cc\u0645 \u067e\u0631\u062f\u0627\u062e\u062a.<\/p>\n<h3>\u0639\u0644\u0644 \u0639\u062f\u0645 \u0634\u0646\u06cc\u062f\u0646 \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647<\/h3>\n<h4>\u06f1\u066b \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u062f\u0633\u062a\u06af\u0627\u0647<\/h4>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0628\u062a\u062f\u0627\u06cc\u06cc\u200c\u062a\u0631\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0644\u06cc \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627\u0639\u062b \u0639\u062f\u0645 \u0634\u0646\u06cc\u062f\u0646 \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u062f\u0631 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0634\u0648\u062f\u060c \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0646\u0627\u062f\u0631\u0633\u062a \u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u0633\u062a. \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0635\u062f\u0627 \u062f\u0631 \u06af\u0648\u0634\u06cc \u0634\u0645\u0627 \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u062a\u0646\u0638\u06cc\u0645 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0641\u062a\u0647 \u06cc\u0627 \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u062e\u0627\u0645\u0648\u0634 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f. \u0628\u0631\u0627\u06cc \u0628\u0631\u0631\u0633\u06cc \u0627\u06cc\u0646 \u0645\u0633\u0626\u0644\u0647\u060c \u0628\u0647 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0635\u062f\u0627 \u0631\u0641\u062a\u0647 \u0648 \u0627\u0632 \u0645\u0642\u062f\u0627\u0631 \u0628\u0644\u0646\u062f\u06cc \u0635\u062f\u0627 \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0627\u06af\u0631 \u0627\u0632 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u0628\u0631\u0627\u06cc \u067e\u062e\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f\u060c \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0622\u0646 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631 \u0631\u0627 \u0646\u06cc\u0632 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n<h4>\u06f2\u066b \u0645\u0634\u06a9\u0644 \u062f\u0631 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc<\/h4>\n<p>\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0639\u06cc\u0628 \u0648 \u062e\u0631\u0627\u0628\u06cc \u062f\u0631 \u062e\u0648\u062f \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0628\u0627\u0634\u062f. \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0631\u0627\u06cc\u0648\u0631\u0647\u0627\u06cc \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u062e\u0631\u0627\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062a\u0646\u0647\u0627 \u0635\u062f\u0627\u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u0631\u0627 \u067e\u062e\u0634 \u06a9\u0646\u062f \u0648 \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u0631\u0627 \u0645\u0646\u062a\u0642\u0644 \u0646\u06a9\u0646\u062f. \u0628\u0631\u0627\u06cc \u0628\u0631\u0631\u0633\u06cc \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0631\u0627 \u0628\u0647 \u06cc\u06a9 \u062f\u0633\u062a\u06af\u0627\u0647 \u062f\u06cc\u06af\u0631 \u0645\u062a\u0635\u0644 \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0628\u06cc\u0646\u06cc\u062f \u0622\u06cc\u0627 \u0645\u0634\u06a9\u0644 \u0647\u0645\u0686\u0646\u0627\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06cc\u0627 \u062e\u06cc\u0631. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062a\u0645\u06cc\u0632 \u06a9\u0631\u062f\u0646 \u062c\u06a9 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0648 \u0628\u0631\u0631\u0633\u06cc \u0648\u062c\u0648\u062f \u06af\u0631\u062f \u0648 \u063a\u0628\u0627\u0631 \u06cc\u0627 \u06a9\u062b\u06cc\u0641\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062d\u0644 \u0645\u0634\u06a9\u0644 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/p>\n<h4>\u06f3\u066b \u0641\u0627\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc<\/h4>\n<p>\u06af\u0627\u0647\u06cc \u0627\u0648\u0642\u0627\u062a\u060c \u0645\u0634\u06a9\u0644 \u062f\u0631 \u062e\u0648\u062f \u0641\u0627\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u0627\u0633\u062a. \u0627\u06af\u0631 \u0641\u0627\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u0634\u0645\u0627 \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u06a9\u062f\u06af\u0630\u0627\u0631\u06cc \u0646\u0634\u062f\u0647 \u0628\u0627\u0634\u0646\u062f \u06cc\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u067e\u0627\u06cc\u06cc\u0646\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u0628\u0647 \u0648\u0636\u0648\u062d \u0634\u0646\u06cc\u062f\u0647 \u0646\u0634\u0648\u062f. \u062f\u0631 \u0627\u06cc\u0646\u062c\u0627\u060c \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0627\u0632 \u0641\u0627\u06cc\u0644\u200c\u0647\u0627\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u0627\u06cc\u06cc\u062f \u0648 \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f \u06a9\u0647 \u0641\u0627\u06cc\u0644\u200c\u0647\u0627 \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u062f\u0627\u0646\u0644\u0648\u062f \u0634\u062f\u0647\u200c\u0627\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0628\u0631\u0631\u0633\u06cc \u0641\u0631\u0645\u062a \u0641\u0627\u06cc\u0644 \u0646\u06cc\u0632 \u0645\u0647\u0645 \u0627\u0633\u062a\u061b \u0628\u0631\u062e\u06cc \u0641\u0631\u0645\u062a\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u062f\u0633\u062a\u06af\u0627\u0647 \u0634\u0645\u0627 \u0633\u0627\u0632\u06af\u0627\u0631 \u0646\u0628\u0627\u0634\u0646\u062f.<\/p>\n<h4>\u06f4\u066b \u0645\u0634\u06a9\u0644\u0627\u062a \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u06cc<\/h4>\n<p>\u0645\u0634\u06a9\u0644\u0627\u062a \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0627\u062e\u062a\u0644\u0627\u0644 \u062f\u0631 \u067e\u062e\u0634 \u0635\u062f\u0627 \u0634\u0648\u0646\u062f. \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631 \u067e\u062e\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0634\u0645\u0627 \u0628\u0647 \u0631\u0648\u0632 \u0646\u0628\u0627\u0634\u062f \u06cc\u0627 \u0628\u0627 \u0633\u06cc\u0633\u062a\u0645 \u0639\u0627\u0645\u0644 \u062f\u0633\u062a\u06af\u0627\u0647 \u0634\u0645\u0627 \u0633\u0627\u0632\u06af\u0627\u0631 \u0646\u0628\u0627\u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a\u060c \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631 \u0631\u0627 \u0628\u0647 \u0631\u0648\u0632 \u06a9\u0646\u06cc\u062f \u06cc\u0627 \u0627\u0632 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631 \u062f\u06cc\u06af\u0631\u06cc \u0628\u0631\u0627\u06cc \u067e\u062e\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u0627\u06cc\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0631\u06cc\u0633\u062a \u06a9\u0631\u062f\u0646 \u062f\u0633\u062a\u06af\u0627\u0647 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062d\u0644 \u0627\u06cc\u0646 \u0645\u0634\u06a9\u0644 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/p>\n<h3>\u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc<\/h3>\n<h4>\u06f1\u066b \u0628\u0631\u0631\u0633\u06cc \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0635\u062f\u0627<\/h4>\n<p>\u0627\u0648\u0644\u06cc\u0646 \u0642\u062f\u0645 \u0628\u0631\u0627\u06cc \u062d\u0644 \u0645\u0634\u06a9\u0644\u060c \u0628\u0631\u0631\u0633\u06cc \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0635\u062f\u0627 \u0627\u0633\u062a. \u0628\u0647 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u06af\u0648\u0634\u06cc \u0631\u0641\u062a\u0647 \u0648 \u0627\u0632 \u0645\u0642\u062f\u0627\u0631 \u0628\u0644\u0646\u062f\u06cc \u0635\u062f\u0627 \u0648 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0627\u06a9\u0648\u0644\u0627\u06cc\u0632\u0631 \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f. \u0627\u06af\u0631 \u0627\u0632 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u0647\u0627\u06cc \u067e\u062e\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f\u060c \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0622\u0646 \u0631\u0627 \u0646\u06cc\u0632 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u062f. \u0628\u0631\u062e\u06cc \u0627\u0632 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u0647\u0627 \u0627\u0645\u06a9\u0627\u0646 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u06a9\u06cc\u0641\u06cc\u062a \u0635\u062f\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/p>\n<h4>\u06f2\u066b \u062a\u0639\u0648\u06cc\u0636 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc<\/h4>\n<p>\u0627\u06af\u0631 \u067e\u0633 \u0627\u0632 \u0628\u0631\u0631\u0633\u06cc \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u062a\u0644\u0627\u0634 \u0628\u0631\u0627\u06cc \u062d\u0644 \u0645\u0634\u06a9\u0644\u060c \u0647\u0646\u0648\u0632 \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u0631\u0627 \u0646\u0645\u06cc\u200c\u0634\u0646\u0648\u06cc\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0634\u0645\u0627 \u0645\u0634\u06a9\u0644 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a\u060c \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u06cc\u06a9 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u062c\u062f\u06cc\u062f \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f \u0648 \u0622\u0646 \u0631\u0627 \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u06cc\u06a9 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u062f\u06cc\u06af\u0631 \u0628\u0627 \u0647\u0645\u0627\u0646 \u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u0627\u06cc\u06cc\u062f \u062a\u0627 \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f \u06a9\u0647 \u0645\u0634\u06a9\u0644 \u062f\u0631 \u062e\u0648\u062f \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0627\u0633\u062a \u06cc\u0627 \u062e\u06cc\u0631.<\/p>\n<h4>\u06f3\u066b \u0628\u0631\u0631\u0633\u06cc \u0641\u0627\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc<\/h4>\n<p>\u0627\u06af\u0631 \u0627\u0632 \u0641\u0627\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u062f\u0627\u0646\u0644\u0648\u062f \u0634\u062f\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f\u060c \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0641\u0627\u06cc\u0644\u200c\u0647\u0627 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u0645\u0639\u062a\u0628\u0631 \u062f\u0627\u0646\u0644\u0648\u062f \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0646\u0627\u0633\u0628\u06cc \u062f\u0627\u0631\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0641\u0631\u0645\u062a \u0641\u0627\u06cc\u0644 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u062f \u0648 \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f \u06a9\u0647 \u0628\u0627 \u062f\u0633\u062a\u06af\u0627\u0647 \u0634\u0645\u0627 \u0633\u0627\u0632\u06af\u0627\u0631 \u0627\u0633\u062a. \u062f\u0631 \u0635\u0648\u0631\u062a \u0646\u06cc\u0627\u0632\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0641\u0627\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u0631\u0627 \u0628\u0647 \u0641\u0631\u0645\u062a\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0646\u06cc\u062f.<\/p>\n<h4>\u06f4\u066b \u0628\u0647\u200c\u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631<\/h4>\n<p>\u0647\u0645\u06cc\u0634\u0647 \u0645\u0637\u0645\u0626\u0646 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u0647\u0627\u06cc \u067e\u062e\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0648 \u0633\u06cc\u0633\u062a\u0645 \u0639\u0627\u0645\u0644 \u062f\u0633\u062a\u06af\u0627\u0647 \u0634\u0645\u0627 \u0628\u0647 \u0631\u0648\u0632 \u0645\u06cc \u0628\u0627\u0634\u0646\u062f. \u0628\u0647\u200c\u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u0648 \u0631\u0641\u0639 \u0645\u0634\u06a9\u0644\u0627\u062a \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a \u0646\u06cc\u0627\u0632\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u0647\u0627\u06cc \u067e\u062e\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u062f\u06cc\u06af\u0631\u06cc \u0631\u0627 \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0627\u0631\u0627\u06cc \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u0628\u0647\u062a\u0631\u06cc \u0628\u0627\u0634\u0646\u062f.<\/p>\n<h3>\u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a \u0622\u06cc\u0646\u062f\u0647<\/h3>\n<h4>\u06f1\u066b \u0627\u0646\u062a\u062e\u0627\u0628 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0645\u0646\u0627\u0633\u0628<\/h4>\n<p>\u0627\u0646\u062a\u062e\u0627\u0628 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0633\u0627\u0632\u06af\u0627\u0631 \u0628\u0627 \u062f\u0633\u062a\u06af\u0627\u0647 \u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0628\u0631\u0648\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u062f. \u0647\u0646\u062f\u0632\u0641\u0631\u06cc\u200c\u0647\u0627\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u062f\u0627\u0631\u0627\u06cc \u062f\u0631\u0627\u06cc\u0648\u0631\u0647\u0627\u06cc \u0642\u0648\u06cc\u200c\u062a\u0631\u06cc \u0645\u06cc \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u0631\u0627 \u0628\u0647\u062a\u0631 \u0645\u0646\u062a\u0642\u0644 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062a\u0648\u062c\u0647 \u0628\u0647 \u062c\u0632\u0626\u06cc\u0627\u062a \u0645\u0627\u0646\u0646\u062f \u0637\u0648\u0644 \u06a9\u0627\u0628\u0644 \u0648 \u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u062c\u0631\u0628\u0647 \u06af\u0648\u0634 \u062f\u0627\u062f\u0646 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0628\u062e\u0634\u062f.<\/p>\n<h4>\u06f2\u066b \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0627\u0632 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc<\/h4>\n<p>\u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0632 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0639\u0645\u0631 \u0622\u0646 \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u0633\u0639\u06cc \u06a9\u0646\u06cc\u062f \u0627\u0632 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc\u200c\u0647\u0627 \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0646\u0627\u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u06a9\u0646\u06cc\u062f \u0648 \u0622\u0646\u0647\u0627 \u0631\u0627 \u0627\u0632 \u0641\u0634\u0627\u0631\u060c \u0631\u0637\u0648\u0628\u062a \u0648 \u062d\u0631\u0627\u0631\u062a \u062f\u0648\u0631 \u0646\u06af\u0647 \u062f\u0627\u0631\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062a\u0645\u06cc\u0632 \u06a9\u0631\u062f\u0646 \u062f\u0648\u0631\u0647\u200c\u0627\u06cc \u0647\u0646\u062f\u0632\u0641\u0631\u06cc\u200c\u0647\u0627 \u0628\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062a\u062c\u0645\u0639 \u06af\u0631\u062f \u0648 \u063a\u0628\u0627\u0631 \u0648 \u06a9\u062b\u06cc\u0641\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h4>\u06f3\u066b \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631<\/h4>\n<p>\u0647\u0645\u06cc\u0634\u0647 \u0627\u0632 \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u0628\u0631\u0627\u06cc \u067e\u062e\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u0627\u06cc\u06cc\u062f. \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0639\u0631\u0648\u0641 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0628\u0647 \u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc\u200c\u0647\u0627\u06cc \u0645\u0646\u0638\u0645 \u062f\u0627\u0631\u0646\u062f \u0648 \u0627\u0632 \u0646\u0638\u0631 \u0633\u0627\u0632\u06af\u0627\u0631\u06cc \u0645\u0634\u06a9\u0644\u0627\u062a \u06a9\u0645\u062a\u0631\u06cc \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u062e\u062f\u0645\u0627\u062a \u0627\u0633\u062a\u0631\u06cc\u0645 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u0627\u06cc\u06cc\u062f \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0647\u062a\u0631\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f.<\/p>\n<h4>\u06f4\u066b \u062a\u0648\u062c\u0647 \u0628\u0647 \u0628\u0647\u200c\u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc\u200c\u0647\u0627<\/h4>\n<p>\u0647\u0645\u06cc\u0634\u0647 \u0628\u0647 \u0628\u0647\u200c\u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc\u200c\u0647\u0627\u06cc \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u06cc \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0622\u0646\u0647\u0627 \u0631\u0627 \u0628\u0647 \u0645\u0648\u0642\u0639 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f. \u0628\u0647\u200c\u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0634\u0627\u0645\u0644 \u0631\u0641\u0639 \u0645\u0634\u06a9\u0644\u0627\u062a \u0627\u0645\u0646\u06cc\u062a\u06cc \u0648 \u0628\u0647\u0628\u0648\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631 \u0645\u06cc \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u06a9\u06cc\u0641\u06cc\u062a \u0635\u062f\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/p>\n<h2>\u062c\u062f\u0648\u0644 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641<\/h2>\n<table>\n<tr>\n<th>\u0645\u062f\u0644 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc<\/th>\n<th>\u06a9\u06cc\u0641\u06cc\u062a \u0635\u062f\u0627<\/th>\n<th>\u0642\u06cc\u0645\u062a<\/th>\n<th>\u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0627\u0636\u0627\u0641\u0647<\/th>\n<\/tr>\n<tr>\n<td>\u0645\u062f\u0644 A<\/td>\n<td>\u0645\u0646\u0627\u0633\u0628<\/td>\n<td>\u06f9\u06f0\u06f0\u06f0\u06f0 \u062a\u0648\u0645\u0627\u0646<\/td>\n<td>\u0645\u06cc\u06a9\u0631\u0648\u0641\u0646\u060c \u06a9\u0646\u062a\u0631\u0644 \u0635\u062f\u0627<\/td>\n<\/tr>\n<tr>\n<td>\u0645\u062f\u0644 B<\/td>\n<td>\u062e\u0648\u0628<\/td>\n<td>\u06f6\u06f0\u06f0\u06f0\u06f0 \u062a\u0648\u0645\u0627\u0646<\/td>\n<td>\u0645\u06cc\u06a9\u0631\u0648\u0641\u0646<\/td>\n<\/tr>\n<tr>\n<td>\u0645\u062f\u0644 C<\/td>\n<td>\u0645\u062a\u0648\u0633\u0637<\/td>\n<td>\u06f3\u06f0\u06f0\u06f0\u06f0 \u062a\u0648\u0645\u0627\u0646<\/td>\n<td>\u0628\u062f\u0648\u0646 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0627\u0636\u0627\u0641\u06cc<\/td>\n<\/tr>\n<\/table>\n<h3>\u0646\u062a\u06cc\u062c\u0647\u200c\u06af\u06cc\u0631\u06cc<\/h3>\n<p>\u0639\u062f\u0645 \u0634\u0646\u06cc\u062f\u0646 \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u062f\u0631 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0634\u06a9\u0644\u0627\u062a \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0627\u0634\u062f. \u0627\u0632 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0646\u0627\u062f\u0631\u0633\u062a \u062f\u0633\u062a\u06af\u0627\u0647 \u0648 \u0645\u0634\u06a9\u0644\u0627\u062a \u0633\u062e\u062a\u200c\u0627\u0641\u0632\u0627\u0631\u06cc \u06af\u0631\u0641\u062a\u0647 \u062a\u0627 \u0641\u0627\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u0628\u06cc\u200c\u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0645\u0634\u06a9\u0644\u0627\u062a \u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631\u06cc. \u0628\u0627 \u0628\u0631\u0631\u0633\u06cc \u062f\u0642\u06cc\u0642 \u0627\u06cc\u0646 \u0645\u0648\u0627\u0631\u062f \u0648 \u0627\u0646\u062c\u0627\u0645 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0644\u0627\u0632\u0645\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u06cc\u0646 \u0645\u0634\u06a9\u0644 \u0631\u0627 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u062d\u0644 \u06a9\u0631\u062f. \u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0645\u0646\u0627\u0633\u0628 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0627\u0632 \u0622\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u06a9\u0647 \u062a\u062c\u0631\u0628\u0647 \u06af\u0648\u0634 \u062f\u0627\u062f\u0646 \u0628\u0647 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0628\u0647\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<p>&#8220;`<\/p>\n<p style=\"text-align: center;\"><strong><a class=\"maxbutton-355 maxbutton maxbutton-d985d8b4d8a7d987d8afdb80-d982db8cd985d8aa-d9bed8b1d981d8b1d988d8b4-d8aad8b1db8cd986-d987d986d8afd8b2d981d8b1db8c-d988-d987d8afd981d988\" target=\"_blank\" title=\"\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc\" rel=\"nofollow noopener\" href=\"https:\/\/dgkl.io\/api\/v1\/Click\/Orujd\"><span class='mb-text'>\u0645\u0634\u0627\u0647\u062f\u06c0 \u0642\u06cc\u0645\u062a \u067e\u0631\u0641\u0631\u0648\u0634 \u062a\u0631\u06cc\u0646 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc<\/span><\/a><\/strong><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;`html \u0686\u0631\u0627 \u062f\u0631 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u0646\u0645\u06cc\u0627\u062f\u061f \u0645\u0642\u062f\u0645\u0647 \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0645\u0631\u0648\u0632\u060c \u0647\u0646\u062f\u0632\u0641\u0631\u06cc\u200c\u0647\u0627 \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0636\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u06af\u0648\u0634 \u062f\u0627\u062f\u0646 \u0628\u0647 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0648 \u062a\u0645\u0627\u0633\u200c\u0647\u0627\u06cc \u062a\u0644\u0641\u0646\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647\u200c\u0627\u0646\u062f. \u0627\u0645\u0627 \u06af\u0627\u0647\u06cc \u0627\u0648\u0642\u0627\u062a \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u0645\u0634\u06a9\u0644\u06cc \u0645\u0648\u0627\u062c\u0647 \u0634\u0648\u06cc\u0645 \u06a9\u0647 \u0635\u062f\u0627\u06cc \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u06cc\u0627 \u0635\u062f\u0627\u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u0627\u0632 \u0622\u0647\u0646\u06af\u200c\u0647\u0627 \u0628\u0647 \u06af\u0648\u0634 \u0645\u0627 \u0646\u0631\u0633\u062f. \u0627\u06cc\u0646 \u0645\u0634\u06a9\u0644 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0644\u0627\u06cc\u0644 \u0645\u062e\u062a\u0644\u0641\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-67240","post","type-post","status-publish","format-standard","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/posts\/67240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/comments?post=67240"}],"version-history":[{"count":0,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/posts\/67240\/revisions"}],"wp:attachment":[{"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/media?parent=67240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/categories?post=67240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/parsalab.com\/blog\/wp-json\/wp\/v2\/tags?post=67240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}